{"id":5689,"date":"2022-07-15T12:08:49","date_gmt":"2022-07-15T10:08:49","guid":{"rendered":"https:\/\/www.xn--hbs-frth-b6a.de\/?p=5689"},"modified":"2022-07-15T12:08:51","modified_gmt":"2022-07-15T10:08:51","slug":"der-faktor-mensch-spielt-die-wichtigste-rolle","status":"publish","type":"post","link":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/der-faktor-mensch-spielt-die-wichtigste-rolle\/","title":{"rendered":"Der Faktor Mensch spielt die wichtigste Rolle"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_row column_structure=&#8220;3_4,1_4&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_column type=&#8220;3_4&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_text _builder_version=&#8220;4.0.6&#8243; hover_enabled=&#8220;0&#8243;]<\/p>\n<h3>Achim Kopp und Dominic Bylitza informieren HBS-Sch\u00fcler \u00fcber ihre Firmenphilosophie<\/h3>\n<p>\u00dcber die Erfolge oder Misserfolge eines Unternehmens oder einer Firma machen sich die wenigsten Menschen Gedanken. \u201eGut geplant\u201c oder \u201efalsch kalkuliert\u201c sind die g\u00e4ngigen Floskeln, um die beiden Szenarien zu kommentieren. Dass hinter einer erfolgreichen Unternehmensf\u00fchrung weit mehr steckt als gute Planung, richtige Entscheidungen oder gar Gl\u00fcck, machten Achim Kopp und Dominic Bylitza den Zehntkl\u00e4sslern der Heinrich-B\u00f6ll-Schule klar. Auf Einladung von Schulpfarrerin Barbara Holzapfel-Hesselmann waren die beiden Firmeninhaber an die integrierte Gesamtschule gekommen, um \u00fcber ihre Gesch\u00e4ftsphilosophie zu referieren. Beide machten den Sch\u00fclern klar, wie wichtig der Faktor Mensch und ein vertrauensvoller Umgang miteinander f\u00fcr den Erfolg ist.<\/p>\n<p>Vor 52 Jahren begann die Geschichte der Schleiftechnik und Werkzeugschleiferei Kopp in Winterkasten. Sein Vater, so Achim Kopp, habe in einer Garage den Start gewagt. Inzwischen ist die dritte Generation in das Unternehmen involviert. Im Gespr\u00e4ch mit den Sch\u00fclern informierte Kopp \u00fcber die essentiellen Grundlagen f\u00fcr eine erfolgreiche Gesch\u00e4ftsf\u00fchrung. Es sei wichtig, jedem Mitarbeiter die M\u00f6glichkeit zu geben, sich und seine Ideen einzubringen. F\u00fcr Achim Kopp ist die Wertsch\u00e4tzung der Mitarbeiter von besonderer Bedeutung. Diese Einstellung beruht auf seiner christlichen Sozialisierung.<\/p>\n<p>Interessant war f\u00fcr die Jugendlichen, nach welchen Kriterien die Firma Kopp ihre Auszubildenden aussucht. Wichtig sei, so Kopp ausf\u00fchrend, dass der Auszubildende menschlich in das Unternehmen passt, deshalb sei ein Praktikum der beste Weg, um dies herauszufinden. Dass die Bewerber wissen sollten, was die jeweilige Firma herstellt und welche Ausbildungsm\u00f6glichkeiten existieren, ist f\u00fcr Achim Kopp eine Selbstverst\u00e4ndlichkeit. Der erfolgreiche Unternehmer hob in seinem Referat auch hervor, dass man sich stets an den W\u00fcnschen der Kunden orientieren m\u00fcsse. Ein respektvolles Miteinander sei ein Garant des Erfolges.<\/p>\n<p>In \u00e4hnlicher Weise \u00e4u\u00dferte sich der Inhaber des F\u00fcrther Edeka-Marktes, Dominic Bylitza. Er hat ein klares Unternehmensleitbild entwickelt, dass er seinen Mitarbeitern transparent vermittelt. Freude, Engagement und eine soziale Einstellung spielen bei der Au\u00dfendarstellung eine wichtige Rolle. Die Pr\u00e4sentation nach au\u00dfen ist ein Faktor, mindestens ebenso wichtig ist ein internes harmonisches Miteinander. Daf\u00fcr seien unter anderem, so Dominic Bylitza ausf\u00fchrend, eine hohe Wertsch\u00e4tzung, Vertrauen oder Zuverl\u00e4ssigkeit unabdingbar.<\/p>\n<p>Eine Verbindung vieler solcher Werte f\u00fchre letztlich, das zeigte Bylitza anhand einer Grafik, zu \u201eRespekt, Qualit\u00e4t und Verantwortung\u201c. Auf diesen drei Pfeilern ruht das Gesch\u00e4ftsmodell des Edeka-Marktes in F\u00fcrth. Dominic Bylitza gew\u00e4hrte den Sch\u00fclern auch einen Einblick in seinen breit gef\u00e4cherten Verantwortungsbereich, der von der Kundenbetreuung \u00fcber den Lebensmitteleinkauf bis hin zur F\u00fchrung seiner Mitarbeiter reicht. Er betonte zudem, dass er nicht nur f\u00fcr seinen Betrieb, sondern auch f\u00fcr das gesellschaftliche Leben als B\u00fcrger Verantwortung \u00fcbernehme. \u00a0<\/p>\n<p>Die Zehntkl\u00e4ssler waren sichtlich beeindruckt von den beiden Unternehmern, deren Erfolg klaren Leitlinien verdanken, die wiederum auf christlich-sozialen Werten basieren.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5690 aligncenter size-medium\" src=\"https:\/\/www.xn--hbs-frth-b6a.de\/wp-content\/uploads\/2022\/07\/EdekaBylitza1-300x225.jpg\" alt=\"Dominic Bylitza (l.), Betreiber des gleichnamigen Edeka-Marktes in F\u00fcrth, war zu Gast an der Heinrich-B\u00f6ll-Schule, um den Jugendlichen die Philosophie seines Marktes zu erl\u00e4utern.\" width=\"300\" height=\"225\" \/>UNTERNEHMENSPHILOSPHIE. Dominic Bylitza (l.), Betreiber des gleichnamigen Edeka-Marktes in F\u00fcrth, war zu Gast an der Heinrich-B\u00f6ll-Schule, um den Jugendlichen die Philosophie seines Marktes zu erl\u00e4utern.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_blog _builder_version=&#8220;4.0.6&#8243;][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_row column_structure=&#8220;3_4,1_4&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_column type=&#8220;3_4&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_text _builder_version=&#8220;4.0.6&#8243; hover_enabled=&#8220;0&#8243;] Achim Kopp und Dominic Bylitza informieren HBS-Sch\u00fcler \u00fcber ihre Firmenphilosophie \u00dcber die Erfolge oder Misserfolge eines Unternehmens oder einer Firma machen sich die wenigsten Menschen Gedanken. \u201eGut geplant\u201c oder \u201efalsch kalkuliert\u201c sind die g\u00e4ngigen Floskeln, um die beiden Szenarien zu kommentieren. Dass hinter einer erfolgreichen Unternehmensf\u00fchrung [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/posts\/5689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/comments?post=5689"}],"version-history":[{"count":2,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/posts\/5689\/revisions"}],"predecessor-version":[{"id":5693,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/posts\/5689\/revisions\/5693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/media\/5690"}],"wp:attachment":[{"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/media?parent=5689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/categories?post=5689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/tags?post=5689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}