{"id":2582,"date":"2020-04-07T08:20:58","date_gmt":"2020-04-07T06:20:58","guid":{"rendered":"https:\/\/www.xn--hbs-frth-b6a.de\/?p=2582"},"modified":"2020-04-13T16:24:19","modified_gmt":"2020-04-13T14:24:19","slug":"wir-wuenschen-ein-schoenes-osterfest-und-erholsame-ferien","status":"publish","type":"post","link":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wir-wuenschen-ein-schoenes-osterfest-und-erholsame-ferien\/","title":{"rendered":"Wir w\u00fcnschen ein sch\u00f6nes Osterfest und erholsame Ferien"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_row column_structure=&#8220;3_4,1_4&#8243; _builder_version=&#8220;4.0.6&#8243; hover_enabled=&#8220;0&#8243;][et_pb_column type=&#8220;3_4&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_text _builder_version=&#8220;4.0.6&#8243; hover_enabled=&#8220;0&#8243;]<\/p>\n<pre><strong>\u201eVom Eise befreit sind Strom und B\u00e4che<\/strong>\n<strong>Durch des Fr\u00fchlings holden, bebenden Blick;<\/strong>\n<strong>Im Tale gr\u00fcnet Hoffnungsgl\u00fcck; \u2026<\/strong><\/pre>\n<p>Mit diesen Zeilen beginnt der ber\u00fchmte Osterspaziergang Fausts mit Wagner. Es folgt die Beschreibung der herausgeputzten und fr\u00f6hlichen Menschen, die ihre H\u00e4user verlassen, sich in die aufbl\u00fchende Natur begeben und nach dunklen Wintermonaten den Kontakt mit ihren Mitmenschen suchen.<\/p>\n<p>Die Wetterprognosen verhei\u00dfen auch f\u00fcr das anstehende Osterfest strahlenden Sonnenschein. Doch die Situation ist eine andere als jene in Goethes Faust. Spazierg\u00e4nge sind allenthalben m\u00f6glich \u2013 zu zweit oder in der Familie. Ein geselliges \u201eGet\u00fcmmel\u201c in Dorf oder Stadt, wie Faust es w\u00e4hrend seines Spaziergangs beschreibt, ist nicht erlaubt. Ein Virus hat die Welt ver\u00e4ndert und verhindert den mitmenschlichen Kontakt.<\/p>\n<p>Die Einschnitte in unseren Alltag sind erheblich; auch das Osterfest ist stark davon betroffen. Dennoch: Die jetzige Situation gew\u00e4hrt uns auch neue Lebensgef\u00fchle. Die oft gew\u00fcnschte Entschleunigung ist eingetreten. Viele Menschen haben jetzt etwas, das kaum mehr jemand kannte: Mu\u00dfe. Ein Zustand, der es uns erlaubt, \u00fcber uns selbst nachzudenken, unsere t\u00e4glichen Routinearbeiten zu hinterfragen und neue Lebensperspektiven zu skizzieren.<\/p>\n<p>Aus diesem Grund sollten wir optimistisch in die Zukunft schauen. Wir sollten das Osterfest dazu nutzen, Einkehr zu halten, zu entschleunigen und uns vorzubereiten auf die Zeit nach der Pandemie. Dank neuer Medien k\u00f6nnen wir \u2013 auch wenn es nicht gerade bei einem \u201eGet\u00fcmmel\u201c im Dorf oder in der Stadt ist \u2013 Kontakt mit unseren Angeh\u00f6rigen und Freunden halten. Wir k\u00f6nnen uns im Voraus auf das geregelte Leben und das normale Miteinander nach dieser Auszeit freuen.<\/p>\n<p>Wir w\u00fcnschen Ihnen ein sch\u00f6nes Osterfest, verbunden mit dem derzeit wichtigsten Wunsch: Bleiben Sie gesund!<\/p>\n<p>[\/et_pb_text][et_pb_blurb image=&#8220;https:\/\/www.xn--hbs-frth-b6a.de\/wp-content\/uploads\/2020\/04\/200407_Ostern-scaled.jpg&#8220; _builder_version=&#8220;4.0.6&#8243;]<\/p>\n<p style=\"text-align: center;\"><em>Wir w\u00fcnschen Ihnen ein sch\u00f6nes Osterfest, verbunden mit dem derzeit wichtigsten Wunsch: Bleiben Sie gesund!<\/em><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_blog _builder_version=&#8220;4.0.6&#8243;][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_row column_structure=&#8220;3_4,1_4&#8243; _builder_version=&#8220;4.0.6&#8243; hover_enabled=&#8220;0&#8243;][et_pb_column type=&#8220;3_4&#8243; _builder_version=&#8220;4.0.6&#8243;][et_pb_text _builder_version=&#8220;4.0.6&#8243; hover_enabled=&#8220;0&#8243;] \u201eVom Eise befreit sind Strom und B\u00e4che Durch des Fr\u00fchlings holden, bebenden Blick; Im Tale gr\u00fcnet Hoffnungsgl\u00fcck; \u2026 Mit diesen Zeilen beginnt der ber\u00fchmte Osterspaziergang Fausts mit Wagner. Es folgt die Beschreibung der herausgeputzten und fr\u00f6hlichen Menschen, die ihre H\u00e4user verlassen, sich in die aufbl\u00fchende [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2586,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/posts\/2582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/comments?post=2582"}],"version-history":[{"count":7,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/posts\/2582\/revisions"}],"predecessor-version":[{"id":2598,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/posts\/2582\/revisions\/2598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/media\/2586"}],"wp:attachment":[{"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/media?parent=2582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/categories?post=2582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.xn--hbs-frth-b6a.de\/index.php\/wp-json\/wp\/v2\/tags?post=2582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}